{"id":2256,"count":8,"description":"","link":"https:\/\/www.linvosges-hotellerie.com\/el\/gamme\/vezuvio-el\/","name":"Vezuvio","slug":"vezuvio-el","taxonomy":"gamme","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.linvosges-hotellerie.com\/el\/wp-json\/wp\/v2\/gamme\/2256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.linvosges-hotellerie.com\/el\/wp-json\/wp\/v2\/gamme"}],"about":[{"href":"https:\/\/www.linvosges-hotellerie.com\/el\/wp-json\/wp\/v2\/taxonomies\/gamme"}],"wp:post_type":[{"href":"https:\/\/www.linvosges-hotellerie.com\/el\/wp-json\/wp\/v2\/product?gamme=2256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}